{"id":1,"name":"Stadm","url":"https:\/\/www.sertras.com\/gestao-de-fornecedores","description":"","link":"https:\/\/www.sertras.com\/gestao-de-fornecedores\/author\/stadm\/","slug":"stadm","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/4ce798d0b2a7228fa03988f80bb44c1fd5243d466f89473917b6cc2974300786?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/4ce798d0b2a7228fa03988f80bb44c1fd5243d466f89473917b6cc2974300786?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/4ce798d0b2a7228fa03988f80bb44c1fd5243d466f89473917b6cc2974300786?s=96&d=mm&r=g"},"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Stadm, Autor em Sertras Gest\u00e3o de Fornecedores<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sertras.com\/gestao-de-fornecedores\/author\/stadm\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"profile\" \/>\n<meta property=\"og:title\" content=\"Stadm\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sertras.com\/gestao-de-fornecedores\/author\/stadm\/\" \/>\n<meta property=\"og:site_name\" content=\"Sertras Gest\u00e3o de Fornecedores\" \/>\n<meta property=\"og:image\" content=\"https:\/\/secure.gravatar.com\/avatar\/4ce798d0b2a7228fa03988f80bb44c1fd5243d466f89473917b6cc2974300786?s=500&d=mm&r=g\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"ProfilePage\",\"@id\":\"https:\\\/\\\/www.sertras.com\\\/gestao-de-fornecedores\\\/author\\\/stadm\\\/\",\"url\":\"https:\\\/\\\/www.sertras.com\\\/gestao-de-fornecedores\\\/author\\\/stadm\\\/\",\"name\":\"Stadm, Autor em Sertras Gest\u00e3o de Fornecedores\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sertras.com\\\/gestao-de-fornecedores\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sertras.com\\\/gestao-de-fornecedores\\\/author\\\/stadm\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sertras.com\\\/gestao-de-fornecedores\\\/author\\\/stadm\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sertras.com\\\/gestao-de-fornecedores\\\/author\\\/stadm\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.sertras.com\\\/gestao-de-fornecedores\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arquivos para Stadm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sertras.com\\\/gestao-de-fornecedores\\\/#website\",\"url\":\"https:\\\/\\\/www.sertras.com\\\/gestao-de-fornecedores\\\/\",\"name\":\"Sertras Gest\u00e3o de Fornecedores\",\"description\":\"Servi\u00e7os profissionais para compradores e fornecedores\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sertras.com\\\/gestao-de-fornecedores\\\/#organization\"},\"alternateName\":\"Sertras\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sertras.com\\\/gestao-de-fornecedores\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sertras.com\\\/gestao-de-fornecedores\\\/#organization\",\"name\":\"Sertras Gest\u00e3o de Fornecedores\",\"alternateName\":\"Sertras\",\"url\":\"https:\\\/\\\/www.sertras.com\\\/gestao-de-fornecedores\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.sertras.com\\\/gestao-de-fornecedores\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sertras.com\\\/gestao-de-fornecedores\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Sertras-1080X270-Transparente.png\",\"contentUrl\":\"https:\\\/\\\/www.sertras.com\\\/gestao-de-fornecedores\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Sertras-1080X270-Transparente.png\",\"width\":1080,\"height\":270,\"caption\":\"Sertras Gest\u00e3o de Fornecedores\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sertras.com\\\/gestao-de-fornecedores\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/pt-br.facebook.com\\\/sertras\\\/\",\"https:\\\/\\\/www.instagram.com\\\/sertrasfor\\\/\",\"https:\\\/\\\/br.linkedin.com\\\/company\\\/sertras\",\"https:\\\/\\\/www.sertras.com\\\/gestao-de-fornecedores\\\/\"],\"description\":\"A Sertras \u00e9 a maior autoridade em gest\u00e3o de fornecedores do Brasil, liderando o mercado com um ecossistema completo de governan\u00e7a e mitiga\u00e7\u00e3o de riscos. Especialista em Gest\u00e3o de Terceiros e Auditorias, a Sertras entrega 'Gest\u00e3o de Verdade' atrav\u00e9s de um portf\u00f3lio robusto que inclui Homologa\u00e7\u00e3o t\u00e9cnica, An\u00e1lise Financeira profunda, Due Diligence, Background Check e monitoramento de crit\u00e9rios ESG. Como pioneira na emiss\u00e3o de Selos de Certifica\u00e7\u00e3o e na forma\u00e7\u00e3o de um Ecossistema de Fornecedores Certificados, a companhia combina tecnologia de dados e intelig\u00eancia anal\u00edtica para garantir conformidade, seguran\u00e7a e performance em toda a cadeia de suprimentos das maiores corpora\u00e7\u00f5es do pa\u00eds.\",\"email\":\"comercial@sertras.com\",\"telephone\":\"+552120180156\",\"legalName\":\"Sertras Gest\u00e3o de Fornecedores Limitada\",\"foundingDate\":\"2015-06-03\",\"vatID\":\"22584068000106\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"51\",\"maxValue\":\"200\"},\"publishingPrinciples\":\"https:\\\/\\\/www.sertras.com\\\/gestao-de-fornecedores\\\/politicas-sertras-old\\\/\",\"ethicsPolicy\":\"https:\\\/\\\/www.sertras.com\\\/gestao-de-fornecedores\\\/politicas-sertras-old\\\/\",\"diversityPolicy\":\"https:\\\/\\\/www.sertras.com\\\/gestao-de-fornecedores\\\/politicas-sertras-old\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sertras.com\\\/gestao-de-fornecedores\\\/#\\\/schema\\\/person\\\/61c69120d0da5e8c538a3015791d35d4\",\"name\":\"Stadm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ce798d0b2a7228fa03988f80bb44c1fd5243d466f89473917b6cc2974300786?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ce798d0b2a7228fa03988f80bb44c1fd5243d466f89473917b6cc2974300786?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ce798d0b2a7228fa03988f80bb44c1fd5243d466f89473917b6cc2974300786?s=96&d=mm&r=g\",\"caption\":\"Stadm\"},\"sameAs\":[\"https:\\\/\\\/www.sertras.com\\\/gestao-de-fornecedores\"],\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sertras.com\\\/gestao-de-fornecedores\\\/author\\\/stadm\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Stadm, Autor em Sertras Gest\u00e3o de Fornecedores","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sertras.com\/gestao-de-fornecedores\/author\/stadm\/","og_locale":"pt_BR","og_type":"profile","og_title":"Stadm","og_url":"https:\/\/www.sertras.com\/gestao-de-fornecedores\/author\/stadm\/","og_site_name":"Sertras Gest\u00e3o de Fornecedores","og_image":[{"url":"https:\/\/secure.gravatar.com\/avatar\/4ce798d0b2a7228fa03988f80bb44c1fd5243d466f89473917b6cc2974300786?s=500&d=mm&r=g","type":"","width":"","height":""}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"ProfilePage","@id":"https:\/\/www.sertras.com\/gestao-de-fornecedores\/author\/stadm\/","url":"https:\/\/www.sertras.com\/gestao-de-fornecedores\/author\/stadm\/","name":"Stadm, Autor em Sertras Gest\u00e3o de Fornecedores","isPartOf":{"@id":"https:\/\/www.sertras.com\/gestao-de-fornecedores\/#website"},"breadcrumb":{"@id":"https:\/\/www.sertras.com\/gestao-de-fornecedores\/author\/stadm\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sertras.com\/gestao-de-fornecedores\/author\/stadm\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sertras.com\/gestao-de-fornecedores\/author\/stadm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.sertras.com\/gestao-de-fornecedores\/"},{"@type":"ListItem","position":2,"name":"Arquivos para Stadm"}]},{"@type":"WebSite","@id":"https:\/\/www.sertras.com\/gestao-de-fornecedores\/#website","url":"https:\/\/www.sertras.com\/gestao-de-fornecedores\/","name":"Sertras Gest\u00e3o de Fornecedores","description":"Servi\u00e7os profissionais para compradores e fornecedores","publisher":{"@id":"https:\/\/www.sertras.com\/gestao-de-fornecedores\/#organization"},"alternateName":"Sertras","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sertras.com\/gestao-de-fornecedores\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.sertras.com\/gestao-de-fornecedores\/#organization","name":"Sertras Gest\u00e3o de Fornecedores","alternateName":"Sertras","url":"https:\/\/www.sertras.com\/gestao-de-fornecedores\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.sertras.com\/gestao-de-fornecedores\/#\/schema\/logo\/image\/","url":"https:\/\/www.sertras.com\/gestao-de-fornecedores\/wp-content\/uploads\/2020\/11\/Sertras-1080X270-Transparente.png","contentUrl":"https:\/\/www.sertras.com\/gestao-de-fornecedores\/wp-content\/uploads\/2020\/11\/Sertras-1080X270-Transparente.png","width":1080,"height":270,"caption":"Sertras Gest\u00e3o de Fornecedores"},"image":{"@id":"https:\/\/www.sertras.com\/gestao-de-fornecedores\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/pt-br.facebook.com\/sertras\/","https:\/\/www.instagram.com\/sertrasfor\/","https:\/\/br.linkedin.com\/company\/sertras","https:\/\/www.sertras.com\/gestao-de-fornecedores\/"],"description":"A Sertras \u00e9 a maior autoridade em gest\u00e3o de fornecedores do Brasil, liderando o mercado com um ecossistema completo de governan\u00e7a e mitiga\u00e7\u00e3o de riscos. Especialista em Gest\u00e3o de Terceiros e Auditorias, a Sertras entrega 'Gest\u00e3o de Verdade' atrav\u00e9s de um portf\u00f3lio robusto que inclui Homologa\u00e7\u00e3o t\u00e9cnica, An\u00e1lise Financeira profunda, Due Diligence, Background Check e monitoramento de crit\u00e9rios ESG. Como pioneira na emiss\u00e3o de Selos de Certifica\u00e7\u00e3o e na forma\u00e7\u00e3o de um Ecossistema de Fornecedores Certificados, a companhia combina tecnologia de dados e intelig\u00eancia anal\u00edtica para garantir conformidade, seguran\u00e7a e performance em toda a cadeia de suprimentos das maiores corpora\u00e7\u00f5es do pa\u00eds.","email":"comercial@sertras.com","telephone":"+552120180156","legalName":"Sertras Gest\u00e3o de Fornecedores Limitada","foundingDate":"2015-06-03","vatID":"22584068000106","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"51","maxValue":"200"},"publishingPrinciples":"https:\/\/www.sertras.com\/gestao-de-fornecedores\/politicas-sertras-old\/","ethicsPolicy":"https:\/\/www.sertras.com\/gestao-de-fornecedores\/politicas-sertras-old\/","diversityPolicy":"https:\/\/www.sertras.com\/gestao-de-fornecedores\/politicas-sertras-old\/"},{"@type":"Person","@id":"https:\/\/www.sertras.com\/gestao-de-fornecedores\/#\/schema\/person\/61c69120d0da5e8c538a3015791d35d4","name":"Stadm","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/4ce798d0b2a7228fa03988f80bb44c1fd5243d466f89473917b6cc2974300786?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4ce798d0b2a7228fa03988f80bb44c1fd5243d466f89473917b6cc2974300786?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4ce798d0b2a7228fa03988f80bb44c1fd5243d466f89473917b6cc2974300786?s=96&d=mm&r=g","caption":"Stadm"},"sameAs":["https:\/\/www.sertras.com\/gestao-de-fornecedores"],"mainEntityOfPage":{"@id":"https:\/\/www.sertras.com\/gestao-de-fornecedores\/author\/stadm\/"}}]}},"elementor_introduction":"","_links":{"self":[{"href":"https:\/\/www.sertras.com\/gestao-de-fornecedores\/wp-json\/wp\/v2\/users\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sertras.com\/gestao-de-fornecedores\/wp-json\/wp\/v2\/users"}]}}